{"id":3354,"date":"2022-07-27T14:40:17","date_gmt":"2022-07-27T17:40:17","guid":{"rendered":"https:\/\/www.abgd.com.br\/portal\/?p=3354"},"modified":"2025-09-12T11:34:58","modified_gmt":"2025-09-12T14:34:58","slug":"campo-grande-recebe-forum","status":"publish","type":"post","link":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/","title":{"rendered":"Campo Grande recebe o F\u00f3rum GD Regi\u00e3o Centro Oeste em agosto"},"content":{"rendered":"<p>Capital do Mato Grosso do Sul ser\u00e1 palco de um dos maiores eventos de gera\u00e7\u00e3o distribu\u00edda do pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n<p>A capital do Mato Grosso do Sul (MS), Campo Grande, receber\u00e1 no pr\u00f3ximo m\u00eas a 15\u00aa edi\u00e7\u00e3o do F\u00f3rum Regional de Gera\u00e7\u00e3o Distribu\u00edda na regi\u00e3o Centro-Oeste (F\u00f3rum GD- Regi\u00e3o Centro Oeste). Voltado exclusivamente para o setor GD do pa\u00eds, o evento acontecer\u00e1 entre os dias 09, 10 e 11 de agosto, no Espa\u00e7o Madame Dora, bairro Caicara.<\/p>\n<p>&nbsp;<\/p>\n<p>O evento vem para debater o atual cen\u00e1rio da Gera\u00e7\u00e3o Distribu\u00edda na regi\u00e3o, a qual est\u00e1 crescendo em n\u00fameros expressivos de pot\u00eancia instalada no \u00faltimo ano.\u00a0 Formada pelos estados de Goi\u00e1s, Mato Grosso do Sul, Mato Grosso e Distrito Federal, a regi\u00e3o Centro Oeste soma hoje mais de 1,6 MW de acordo com dados da Ag\u00eancia Nacional de Energia El\u00e9trica (ANEEL).<\/p>\n<p>&nbsp;<\/p>\n<p>O estado que mais produz esse tipo de energia hoje \u00e9 Mato Grosso, que segundo a ag\u00eancia produz sozinho 716 MW de energia. Em seguida vem Goi\u00e1s e Mato Grosso do Sul. O estado que menos gera por enquanto \u00e9 o Distrito Federal com apenas 112 MW.<\/p>\n<p>&nbsp;<\/p>\n<p>Contudo, os dados podem mudar em breve. Isso porque cada vez mais os governos estaduais est\u00e3o investindo em fontes renov\u00e1veis, assim como criando oportunidades para incentiv\u00e1-las. Um dos exemplos vem do MS, palco do F\u00f3rum GD este ano.<\/p>\n<p>&nbsp;<\/p>\n<p>Com um programa de fomento criado pelo estado chamado MS Renov\u00e1vel, a procura por pain\u00e9is solares fotovoltaicos segundo o governo cresceu 25% de dezembro de 2021 a mar\u00e7o de 2022. At\u00e9 2023 o n\u00famero deve dobrar e alavancar o setor ainda mais na regi\u00e3o. As maiores usinas do estado est\u00e3o localizadas em quatro munic\u00edpios sul mato-grossenses, sendo a maioria delas na capital.<\/p>\n<p>&nbsp;<\/p>\n<p>Tiago Fraga, CEO do Grupo FRG M\u00eddias &amp;\u00a0 Eventos destaca que o evento tem tudo para ser o maior do setor no pa\u00eds e movimentar o mercado da regi\u00e3o centro &#8211; oeste.<\/p>\n<p>&nbsp;<\/p>\n<p>\u2018\u2019A expectativa \u00e9 do crescimento do setor na regi\u00e3o centro oeste, em especial do Mato Grosso do Sul , com o aumento de at\u00e9 30% nas vendas de usinas solares fotovoltaicas, ap\u00f3s a passagem do f\u00f3rum GD\u2019\u2019, afirma Fraga.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>O F\u00f3rum GD Centro Oeste<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Diante do cen\u00e1rio de crescimento da regi\u00e3o centro oeste para fonte de gera\u00e7\u00e3o distribu\u00edda, debater o assunto se tornou imprescind\u00edvel para o desenvolvimento do setor. O F\u00f3rum GD &#8211; Centro Oeste vem justamente para sanar essa lacuna, onde in\u00fameros especialistas e players se reunir\u00e3o para debater o assunto.<\/p>\n<p>&nbsp;<\/p>\n<p>A programa\u00e7\u00e3o do f\u00f3rum contar\u00e1 com pain\u00e9is espec\u00edficos. Dentre eles est\u00e3o temas como oportunidades de neg\u00f3cios para os integradores, a import\u00e2ncia da seguran\u00e7a nas usinas FV e tamb\u00e9m o est\u00e1gio atual e futuro dos neg\u00f3cios GD na regi\u00e3o centro-oeste. O\u00a0 evento \u00e9 organizado pelo Grupo FRG M\u00eddias e Eventos, assim como promovido pela Associa\u00e7\u00e3o Brasileira de Gera\u00e7\u00e3o Distribu\u00edda (ABGD).<\/p>\n<p>&nbsp;<\/p>\n<p>\u2018\u2019 Esperamos em m\u00e9dia dois mil participantes nos tr\u00eas dias de evento, que deve reunir grande parte da cadeia produtiva do setor de gera\u00e7\u00e3o distribu\u00edda e energia solar fotovoltaica. Al\u00e9m da participa\u00e7\u00e3o de empresas de mais de 10 pa\u00edses\u2019\u2019, destaca Fraga.<\/p>\n<p>&nbsp;<\/p>\n<p>A edi\u00e7\u00e3o deste ano ser\u00e1 em formato h\u00edbrido e os participantes poder\u00e3o acompanhar as palestras em tempo real atrav\u00e9s da internet e plataforma exclusiva.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cO evento ter\u00e1 a participa\u00e7\u00e3o dos Principais Players, Especialistas do setor e Representantes da Academia. Discutiremos sobre os principais desafios e oportunidades que teremos para o setor de Energia Solar Fotovoltaica e GD Fontes Renov\u00e1veis &#8220;, afirma a organiza\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Os interessados em se inscrever no evento podem acessar o site o F\u00f3rum atrav\u00e9s do link: <a href=\"https:\/\/www.forumgdcentrooeste.com.br\/site\/inscricao\/\">https:\/\/www.forumgdcentrooeste.com.br\/site\/inscricao\/<\/a>. A programa\u00e7\u00e3o completa tamb\u00e9m pode ser acessada atrav\u00e9s do site.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Capital do Mato Grosso do Sul ser\u00e1 palco de um dos maiores eventos de gera\u00e7\u00e3o distribu\u00edda do pa\u00eds. &nbsp; A capital do Mato Grosso do Sul (MS), Campo Grande, receber\u00e1 no pr\u00f3ximo m\u00eas a 15\u00aa edi\u00e7\u00e3o do F\u00f3rum Regional de Gera\u00e7\u00e3o Distribu\u00edda na regi\u00e3o Centro-Oeste (F\u00f3rum GD- Regi\u00e3o Centro Oeste). Voltado exclusivamente para o setor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campo Grande recebe o F\u00f3rum GD Regi\u00e3o Centro Oeste em agosto - ABGD<\/title>\n<meta name=\"description\" content=\"Voltado para o setor GD do pa\u00eds, o evento acontecer\u00e1 entre os dias 09, 10 e 11 de agosto, no Espa\u00e7o Madame Dora, bairro Caicara.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campo Grande recebe o F\u00f3rum GD Regi\u00e3o Centro Oeste em agosto - ABGD\" \/>\n<meta property=\"og:description\" content=\"Voltado para o setor GD do pa\u00eds, o evento acontecer\u00e1 entre os dias 09, 10 e 11 de agosto, no Espa\u00e7o Madame Dora, bairro Caicara.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/\" \/>\n<meta property=\"og:site_name\" content=\"ABGD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Abgdbrasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-27T17:40:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-12T14:34:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2022\/07\/Campo-Grande-recebe-o-Forum-GD-Regiao-Centro-Oeste-em-agosto.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"821\" \/>\n\t<meta property=\"og:image:height\" content=\"833\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"marketing-go\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing-go\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/\"},\"author\":{\"name\":\"marketing-go\",\"@id\":\"https:\/\/www.abgd.com.br\/portal\/#\/schema\/person\/9cd8d7f269f319517f064de637cc7091\"},\"headline\":\"Campo Grande recebe o F\u00f3rum GD Regi\u00e3o Centro Oeste em agosto\",\"datePublished\":\"2022-07-27T17:40:17+00:00\",\"dateModified\":\"2025-09-12T14:34:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/\"},\"wordCount\":697,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.abgd.com.br\/portal\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2022\/07\/Campo-Grande-recebe-o-Forum-GD-Regiao-Centro-Oeste-em-agosto.webp\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/\",\"url\":\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/\",\"name\":\"Campo Grande recebe o F\u00f3rum GD Regi\u00e3o Centro Oeste em agosto - ABGD\",\"isPartOf\":{\"@id\":\"https:\/\/www.abgd.com.br\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2022\/07\/Campo-Grande-recebe-o-Forum-GD-Regiao-Centro-Oeste-em-agosto.webp\",\"datePublished\":\"2022-07-27T17:40:17+00:00\",\"dateModified\":\"2025-09-12T14:34:58+00:00\",\"description\":\"Voltado para o setor GD do pa\u00eds, o evento acontecer\u00e1 entre os dias 09, 10 e 11 de agosto, no Espa\u00e7o Madame Dora, bairro Caicara.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#primaryimage\",\"url\":\"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2022\/07\/Campo-Grande-recebe-o-Forum-GD-Regiao-Centro-Oeste-em-agosto.webp\",\"contentUrl\":\"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2022\/07\/Campo-Grande-recebe-o-Forum-GD-Regiao-Centro-Oeste-em-agosto.webp\",\"width\":821,\"height\":833},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.abgd.com.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campo Grande recebe o F\u00f3rum GD Regi\u00e3o Centro Oeste em agosto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.abgd.com.br\/portal\/#website\",\"url\":\"https:\/\/www.abgd.com.br\/portal\/\",\"name\":\"ABGD\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.abgd.com.br\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.abgd.com.br\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.abgd.com.br\/portal\/#organization\",\"name\":\"ABGD\",\"url\":\"https:\/\/www.abgd.com.br\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.abgd.com.br\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2025\/09\/ABGD-AZUL.webp\",\"contentUrl\":\"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2025\/09\/ABGD-AZUL.webp\",\"width\":641,\"height\":219,\"caption\":\"ABGD\"},\"image\":{\"@id\":\"https:\/\/www.abgd.com.br\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Abgdbrasil\",\"https:\/\/www.instagram.com\/abgd_oficial\/\",\"https:\/\/www.linkedin.com\/company\/abgd\/\",\"https:\/\/www.youtube.com\/@ABGDoficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.abgd.com.br\/portal\/#\/schema\/person\/9cd8d7f269f319517f064de637cc7091\",\"name\":\"marketing-go\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/912ba1de83c4475b871b9b8a259e744e73f252bfd3a806151bf87f961eecfda8?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/912ba1de83c4475b871b9b8a259e744e73f252bfd3a806151bf87f961eecfda8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/912ba1de83c4475b871b9b8a259e744e73f252bfd3a806151bf87f961eecfda8?s=96&d=mm&r=g\",\"caption\":\"marketing-go\"},\"sameAs\":[\"https:\/\/www.abgd.com.br\/portal\"],\"url\":\"https:\/\/www.abgd.com.br\/portal\/author\/marketing-go\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campo Grande recebe o F\u00f3rum GD Regi\u00e3o Centro Oeste em agosto - ABGD","description":"Voltado para o setor GD do pa\u00eds, o evento acontecer\u00e1 entre os dias 09, 10 e 11 de agosto, no Espa\u00e7o Madame Dora, bairro Caicara.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/","og_locale":"pt_BR","og_type":"article","og_title":"Campo Grande recebe o F\u00f3rum GD Regi\u00e3o Centro Oeste em agosto - ABGD","og_description":"Voltado para o setor GD do pa\u00eds, o evento acontecer\u00e1 entre os dias 09, 10 e 11 de agosto, no Espa\u00e7o Madame Dora, bairro Caicara.","og_url":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/","og_site_name":"ABGD","article_publisher":"https:\/\/www.facebook.com\/Abgdbrasil","article_published_time":"2022-07-27T17:40:17+00:00","article_modified_time":"2025-09-12T14:34:58+00:00","og_image":[{"width":821,"height":833,"url":"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2022\/07\/Campo-Grande-recebe-o-Forum-GD-Regiao-Centro-Oeste-em-agosto.webp","type":"image\/webp"}],"author":"marketing-go","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marketing-go","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#article","isPartOf":{"@id":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/"},"author":{"name":"marketing-go","@id":"https:\/\/www.abgd.com.br\/portal\/#\/schema\/person\/9cd8d7f269f319517f064de637cc7091"},"headline":"Campo Grande recebe o F\u00f3rum GD Regi\u00e3o Centro Oeste em agosto","datePublished":"2022-07-27T17:40:17+00:00","dateModified":"2025-09-12T14:34:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/"},"wordCount":697,"commentCount":0,"publisher":{"@id":"https:\/\/www.abgd.com.br\/portal\/#organization"},"image":{"@id":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2022\/07\/Campo-Grande-recebe-o-Forum-GD-Regiao-Centro-Oeste-em-agosto.webp","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/","url":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/","name":"Campo Grande recebe o F\u00f3rum GD Regi\u00e3o Centro Oeste em agosto - ABGD","isPartOf":{"@id":"https:\/\/www.abgd.com.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#primaryimage"},"image":{"@id":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2022\/07\/Campo-Grande-recebe-o-Forum-GD-Regiao-Centro-Oeste-em-agosto.webp","datePublished":"2022-07-27T17:40:17+00:00","dateModified":"2025-09-12T14:34:58+00:00","description":"Voltado para o setor GD do pa\u00eds, o evento acontecer\u00e1 entre os dias 09, 10 e 11 de agosto, no Espa\u00e7o Madame Dora, bairro Caicara.","breadcrumb":{"@id":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#primaryimage","url":"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2022\/07\/Campo-Grande-recebe-o-Forum-GD-Regiao-Centro-Oeste-em-agosto.webp","contentUrl":"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2022\/07\/Campo-Grande-recebe-o-Forum-GD-Regiao-Centro-Oeste-em-agosto.webp","width":821,"height":833},{"@type":"BreadcrumbList","@id":"https:\/\/www.abgd.com.br\/portal\/campo-grande-recebe-forum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.abgd.com.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Campo Grande recebe o F\u00f3rum GD Regi\u00e3o Centro Oeste em agosto"}]},{"@type":"WebSite","@id":"https:\/\/www.abgd.com.br\/portal\/#website","url":"https:\/\/www.abgd.com.br\/portal\/","name":"ABGD","description":"","publisher":{"@id":"https:\/\/www.abgd.com.br\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abgd.com.br\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.abgd.com.br\/portal\/#organization","name":"ABGD","url":"https:\/\/www.abgd.com.br\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.abgd.com.br\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2025\/09\/ABGD-AZUL.webp","contentUrl":"https:\/\/www.abgd.com.br\/portal\/wp-content\/uploads\/2025\/09\/ABGD-AZUL.webp","width":641,"height":219,"caption":"ABGD"},"image":{"@id":"https:\/\/www.abgd.com.br\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Abgdbrasil","https:\/\/www.instagram.com\/abgd_oficial\/","https:\/\/www.linkedin.com\/company\/abgd\/","https:\/\/www.youtube.com\/@ABGDoficial"]},{"@type":"Person","@id":"https:\/\/www.abgd.com.br\/portal\/#\/schema\/person\/9cd8d7f269f319517f064de637cc7091","name":"marketing-go","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/912ba1de83c4475b871b9b8a259e744e73f252bfd3a806151bf87f961eecfda8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/912ba1de83c4475b871b9b8a259e744e73f252bfd3a806151bf87f961eecfda8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/912ba1de83c4475b871b9b8a259e744e73f252bfd3a806151bf87f961eecfda8?s=96&d=mm&r=g","caption":"marketing-go"},"sameAs":["https:\/\/www.abgd.com.br\/portal"],"url":"https:\/\/www.abgd.com.br\/portal\/author\/marketing-go\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abgd.com.br\/portal\/wp-json\/wp\/v2\/posts\/3354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abgd.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abgd.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abgd.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abgd.com.br\/portal\/wp-json\/wp\/v2\/comments?post=3354"}],"version-history":[{"count":1,"href":"https:\/\/www.abgd.com.br\/portal\/wp-json\/wp\/v2\/posts\/3354\/revisions"}],"predecessor-version":[{"id":6182,"href":"https:\/\/www.abgd.com.br\/portal\/wp-json\/wp\/v2\/posts\/3354\/revisions\/6182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abgd.com.br\/portal\/wp-json\/wp\/v2\/media\/6181"}],"wp:attachment":[{"href":"https:\/\/www.abgd.com.br\/portal\/wp-json\/wp\/v2\/media?parent=3354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abgd.com.br\/portal\/wp-json\/wp\/v2\/categories?post=3354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abgd.com.br\/portal\/wp-json\/wp\/v2\/tags?post=3354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}